{"id":286152,"date":"2017-12-31T15:49:49","date_gmt":"2017-12-31T15:49:49","guid":{"rendered":"http:\/\/www.hier-luebeck.de\/besondere-neuigkeiten\/wsp-sh-kollision-beim-anlegen-des-fgs-helgoland-im-suedhafen-auf-helgoland-2157\/"},"modified":"2017-12-31T15:49:49","modified_gmt":"2017-12-31T15:49:49","slug":"wsp-sh-kollision-beim-anlegen-des-fgs-helgoland-im-suedhafen-auf-helgoland-2157","status":"publish","type":"post","link":"https:\/\/hier-luebeck.de\/index.php\/wsp-sh-kollision-beim-anlegen-des-fgs-helgoland-im-suedhafen-auf-helgoland-2157\/","title":{"rendered":"WSP-SH: Kollision beim Anlegen des FGS. &#8222;Helgoland&#8220; im S\u00fcdhafen auf Helgoland"},"content":{"rendered":"<p>Brunsb\u00fcttel \/ Helgoland (ots) &#8211; Am Sonntag, den 31.12.2017, gegen  12.50 Uhr, kam es beim Anlegeman\u00f6ver des FGS. &#8222;Helgoland&#8220; zu einer  Kollision mit der im S\u00fcdhafen Helgolands befindlichen Westkaje. Das  Schiff wollte gerade seine Reise mit 74 Passagieren und 4  Besatzungsmitgliedern an Bord von Cuxhaven nach Helgoland beenden.<!--more-->  Planm\u00e4\u00dfig fuhr die &#8222;Helgoland&#8220; in den S\u00fcdhafen von Helgoland ein und  wollte dort \u00fcber Backbord drehen um an den vorgesehenen Liegeplatz zu gelangen und mit dem Bug voraus in Richtung See anzulegen.     W\u00e4hrend des Drehman\u00f6vers fiel das Bugstrahlruder aus.  Das Schiff  wurde vom Wind erfasst und in Richtung der gegen\u00fcberliegenden Pier  gedr\u00fcckt. Durch den Ausfall des Bugstrahlruders sowie dem  Windeinwirkung gegen die Aufbauten des Schiffes konnte dieses nicht  mehr wie gewohnt man\u00f6vrieren. Eingeleitete Gegenman\u00f6ver konnten einen Zusammensto\u00df nicht verhindern. Auch die Unterst\u00fctzung der vor Ort  befindlichen DGzRS  (Seenotretter &#8222;Hermann Marwede&#8220; mit dem zu Wasser gelassenen Tochterboot &#8222;Verena&#8220;) blieb ohne Erfolg. Die &#8222;Helgoland&#8220;  wurde durch den Wind mit dem Heck gegen die gegen\u00fcberliegende Ostkaje gedr\u00fcckt, wobei ein Sachschaden am Schiff entstand. Durch die  Kollision kam zu keinen Personensch\u00e4den.     Anschlie\u00dfend konnte das Fahrgastschiff sicher an der Ostkaje  festmachen, so dass ein Aussteigen der Passagiere auf die Pier  m\u00f6glich war.     Nach R\u00fccksprache mit der Berufsgenossenschaft Transport und  Verkehr wurde die Weiterfahrt des Schiffes erlaubt, da keine  sicherheitsrelevanten Einrichtungen am Schiff besch\u00e4digt wurden. Die  Ermittlungen dauern an und werden durch die  Wasserschutzpolizeistation Helgoland gef\u00fchrt.   ots Originaltext: Landespolizeiamt Schleswig-Holstein &#8211; Abt. 4 &#8211; Wasserschutzpolizei  Digitale Pressemappe: http:\/\/www.polizeipresse.de\/p_story.htx?firmaid=43800  <\/p>\n<p>Quelle: <a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43800\/3827790\" target=\"_blank\" rel=\"noopener noreferrer\">presseportal.de<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Brunsb\u00fcttel \/ Helgoland (ots) &#8211; Am Sonntag, den 31.12.2017, gegen 12.50 Uhr, kam es beim Anlegeman\u00f6ver des FGS. &#8222;Helgoland&#8220; zu<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[20],"tags":[],"class_list":["post-286152","post","type-post","status-publish","format-standard","hentry","category-besondere-neuigkeiten"],"_links":{"self":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts\/286152","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/comments?post=286152"}],"version-history":[{"count":0,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts\/286152\/revisions"}],"wp:attachment":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/media?parent=286152"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/categories?post=286152"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/tags?post=286152"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}