{"id":291307,"date":"2019-06-06T08:28:24","date_gmt":"2019-06-06T08:28:24","guid":{"rendered":"http:\/\/www.hier-luebeck.de\/besondere-neuigkeiten\/bka-vierter-bundesweiter-aktionstag-gegen-hasspostings-150\/"},"modified":"2019-06-06T08:28:24","modified_gmt":"2019-06-06T08:28:24","slug":"bka-vierter-bundesweiter-aktionstag-gegen-hasspostings-150","status":"publish","type":"post","link":"https:\/\/hier-luebeck.de\/index.php\/bka-vierter-bundesweiter-aktionstag-gegen-hasspostings-150\/","title":{"rendered":"BKA: Vierter bundesweiter Aktionstag gegen Hasspostings"},"content":{"rendered":"<p>Wiesbaden (ots) &#8211; Bedrohungen, N\u00f6tigungen, fremdenfeindliche  Kommentare oder Beleidigungen: Obwohl das Verfassen von  Hasskommentaren kein Kavaliersdelikt ist, kommt es im Internet,  insbesondere in den sozialen Netzwerken, h\u00e4ufig zu hasserf\u00fcllten und  damit auch strafbaren Beitr\u00e4gen.<!--more--> Der heute stattfindende bundesweite  &#8222;Aktionstag zur Bek\u00e4mpfung von Hasspostings&#8220; ist daher wichtiger  Bestandteil des konsequenten Vorgehens von Polizei und Justiz bei der Bek\u00e4mpfung dieses Ph\u00e4nomens.     Seit heute Morgen, 06.00 Uhr, sind Polizeidienststellen in 13  Bundesl\u00e4ndern im Rahmen dieses Aktionstages im Einsatz. In Bayern,  Baden-W\u00fcrttemberg, Berlin, Brandenburg, Bremen, Hessen,  Mecklenburg-Vorpommern, Niedersachsen, Nordrhein-Westfalen,  Rheinland-Pfalz, Schleswig-Holstein, Sachsen-Anhalt und Th\u00fcringen  werden 38 polizeiliche Ma\u00dfnahmen durchgef\u00fchrt, darunter  Wohnungsdurchsuchungen und Vernehmungen. Den T\u00e4tern wird vorgeworfen, Hasskommentare im Internet gepostet zu haben, etwa \u00f6ffentliche  Aufforderungen zur Begehung von Straftaten, Beleidigungen von  Amtspersonen oder antisemitische Beschimpfungen. T\u00e4tern, die solche  strafbaren Inhalte im Netz verbreiten, drohen bis zu f\u00fcnf Jahre Haft.     Der bundesweite Aktionstag zur Bek\u00e4mpfung von Hasspostings wird  vom Bundeskriminalamt als Zentralstelle der deutschen Polizei  koordiniert. Er wurde vor drei Jahren etabliert und findet seitdem  einmal j\u00e4hrlich statt. Das gemeinsame Vorgehen gegen Hass im Netz  zeigt Wirkung: Wurden 2017 in den Fallzahlen zur Politisch  motivierten Kriminalit\u00e4t (PMK) noch 2.270 F\u00e4lle von Hasskommentaren  gez\u00e4hlt, waren es 2018 1.472 F\u00e4lle, ein R\u00fcckgang um 35 Prozent. Ein  Gro\u00dfteil davon (77 Prozent) l\u00e4sst sich dem rechtsextremen Spektrum  zuordnen, knapp 9 Prozent der Kommentare sind linksextrem, die  verbleibenden 14 Prozent sind ausl\u00e4ndischen oder religi\u00f6sen  Ideologien, beziehungsweise keiner konkreten politischen Motivation  zuzuordnen.     Der R\u00fcckgang der Fallzahlen bei den Hasspostings ist eine positive Entwicklung. Um diese fortsetzen zu k\u00f6nnen, sind auch k\u00fcnftig  operative wie pr\u00e4ventive Projekte des Bundes, der L\u00e4nder und auch  nichtstaatlicher Organisationen (NGOs) erforderlich, um Hass im Netz  wirkungsvoll entgegenzutreten. Jeder kann einen Beitrag zur  Bek\u00e4mpfung von Hass im Netz leisten. Das Bundeskriminalamt ruft dazu  auf, Hass, Hetze und verbale Gewalt konsequent bei der Polizei  anzuzeigen. Einige Bundesl\u00e4nder halten daf\u00fcr Internetportale bereit,  \u00fcber die jeder solche Straftaten auch anonym anzeigen kann. Diese  Portale finden Sie auf der Webseite des Bundeskriminalamts: (www.bka. de\/DE\/KontaktAufnehmen\/Strafanzeigen\/strafanzeigen_node.html) oder  auf dem Internetportal der deutschen Polizei: www.polizei.de.     Weitere Informationen erhalten Interessierte im Laufe des Tages  \u00fcber die Social Media-Kan\u00e4le des Bundeskriminalamts. Ausk\u00fcnfte zu den polizeilichen Ma\u00dfnahmen in den am Aktionstag beteiligten  Bundesl\u00e4ndern erteilen die regional zust\u00e4ndigen Polizei- und  Justizbeh\u00f6rden.     <\/p>\n<p>Quelle: <a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/7\/4290212\" target=\"_blank\" rel=\"noopener noreferrer\">presseportal.de<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wiesbaden (ots) &#8211; Bedrohungen, N\u00f6tigungen, fremdenfeindliche Kommentare oder Beleidigungen: Obwohl das Verfassen von Hasskommentaren kein Kavaliersdelikt ist, kommt es im<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[20],"tags":[],"class_list":["post-291307","post","type-post","status-publish","format-standard","hentry","category-besondere-neuigkeiten"],"_links":{"self":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts\/291307","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/comments?post=291307"}],"version-history":[{"count":0,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts\/291307\/revisions"}],"wp:attachment":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/media?parent=291307"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/categories?post=291307"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/tags?post=291307"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}