{"id":341161,"date":"2020-01-30T10:37:13","date_gmt":"2020-01-30T10:37:13","guid":{"rendered":"https:\/\/www.hier-luebeck.de\/index.php\/pol-sh-afb-presseeinladung-feierliche-ernennung-von-jungen-polizeibeamten-nach-erfolgreich-bestandener-pruefung-113\/"},"modified":"2020-01-30T10:37:13","modified_gmt":"2020-01-30T10:37:13","slug":"pol-sh-afb-presseeinladung-feierliche-ernennung-von-jungen-polizeibeamten-nach-erfolgreich-bestandener-pruefung-113","status":"publish","type":"post","link":"https:\/\/hier-luebeck.de\/index.php\/pol-sh-afb-presseeinladung-feierliche-ernennung-von-jungen-polizeibeamten-nach-erfolgreich-bestandener-pruefung-113\/","title":{"rendered":"POL-SH-AFB: Presseeinladung &#8211; Feierliche Ernennung von jungen Polizeibeamten nach erfolgreich bestandener Pr\u00fcfung"},"content":{"rendered":"<p>Eutin (ots) &#8211; Zum Monatsende werden nach zweieinhalb Jahren Ausbildungszeit  voraussichtlich 73 Polizeivollzugsbeamtinnen und -beamte ihre Ausbildung bei der Landespolizei beenden. Im Beisein des Herrn Ministerpr\u00e4sidenten Daniel G\u00fcnther  erfolgt die feierliche Ernennung zur Polizeiobermeisterin bzw. zum  Polizeiobermeister, sowie die Ehrung der Jahrgangsbesten. Die Gru\u00dfworte spricht  u.a.<!--more--> der Landespolizeidirektor Michael Wilksen. Die Festansprache h\u00e4lt J\u00fcrgen  Oelbeck, stellvertretender Leiter der Fachinspektion Aus- und Fortbildung. Durch zwei Auszubildende wird es einen R\u00fcckblick auf die Ausbildungszeit geben, ein  musikalisches Duo erg\u00e4nzt das Programm.  Die Veranstaltung findet zum ersten Mal im Seehotel Maritim,                     Strandallee 73, 23669 Timmendorfer Strand statt. Sie beginnt am Freitag,  31.01.2020, um 14 Uhr, Einlass ist um 13:30 Uhr.  Medienvertreter sind zur Veranstaltung herzlich eingeladen.                      Um Anmeldung bis zum 31.01.2020, 10 Uhr, unter der Emailanschrift  sb11.eutin.pdafb@polizei.landsh.de  wird gebeten.  <\/p>\n<p>Quelle: <a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43685\/4506471\" target=\"_blank\" rel=\"noopener noreferrer\">presseportal.de<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Eutin (ots) &#8211; Zum Monatsende werden nach zweieinhalb Jahren Ausbildungszeit voraussichtlich 73 Polizeivollzugsbeamtinnen und -beamte ihre Ausbildung bei der Landespolizei<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[20],"tags":[],"class_list":["post-341161","post","type-post","status-publish","format-standard","hentry","category-besondere-neuigkeiten"],"_links":{"self":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts\/341161","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/comments?post=341161"}],"version-history":[{"count":0,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts\/341161\/revisions"}],"wp:attachment":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/media?parent=341161"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/categories?post=341161"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/tags?post=341161"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}