{"id":346627,"date":"2019-10-11T12:49:19","date_gmt":"2019-10-11T12:49:19","guid":{"rendered":"https:\/\/www.hier-luebeck.de\/index.php\/bpoli-see-katamaransegler-bei-dunkelheit-aus-der-ostsee-geborgen-358\/"},"modified":"2019-10-11T12:49:19","modified_gmt":"2019-10-11T12:49:19","slug":"bpoli-see-katamaransegler-bei-dunkelheit-aus-der-ostsee-geborgen-358","status":"publish","type":"post","link":"https:\/\/hier-luebeck.de\/index.php\/bpoli-see-katamaransegler-bei-dunkelheit-aus-der-ostsee-geborgen-358\/","title":{"rendered":"BPOLI-See: Katamaransegler bei Dunkelheit aus der Ostsee geborgen"},"content":{"rendered":"<p><img decoding=\"async\" class=\"alignleft size-full\" title=\"Der gekenterte Katamaran\" src=\"https:\/\/cache.pressmailing.net\/thumbnail\/story_big\/5198eac7-78a8-4d16-a98c-2cdfe3988dd7\/6a795cbe-1d77-49a1-a7fa-e40df35397c4.JPG\" \/><\/p>\n<p>Neustadt (ots) &#8211;     Am Donnerstagabend konnte die Besatzung des Bundespolizeibootes BP 65 &#8222;RH\u00d6N II&#8220; einen Segler aus der 14\u00b0 C kalten Ostsee retten. Das  Bundespolizeiboot befand sich kurz vor Eckernf\u00f6rde, als das  Seenotrettungsboot &#8222;ECKERNF\u00d6RDE&#8220; der Deutschen Gesellschaft zur  Rettung Schiffbr\u00fcchiger (DGzRS) die &#8222;RH\u00d6N II&#8220; um Unterst\u00fctzung bat.<!--more-->  Im Seegebiet vor Surendorf war ein Katamaran gekentert und eine  Person befand sich schwimmend im Wasser. Gemeinsam liefen beide Boote mit H\u00f6chstgeschwindigkeit in das Einsatzgebiet in der Eckernf\u00f6rder  Bucht vor Surendorf. Weitere Einsatzkr\u00e4fte wurden alarmiert und waren im Zulauf. Gegen 19:50 Uhr konnte durch BP 65 &#8222;RH\u00d6N II&#8220; der  gekenterte Katamaran sowie eine m\u00e4nnliche Person im Wasser gesichtet  werden. Sofort wurden Ma\u00dfnahmen eingeleitet und der junge Mann aus  dem Wasser gerettet. Es handelte sich um einen 23.j\u00e4hrigen Mann, der  ansprechbar, aber stark unterk\u00fchlt war. Nach seiner Auskunft befand  er sich alleine an Bord des Katamarans und seit insgesamt 2 Stunden  im Wasser. Nach Erstversorgung der Person an Bord lief das  Bundespolizeiboot BP 65 &#8222;RH\u00d6N II&#8220; anschlie\u00dfend sofort Eckernf\u00f6rde an  und \u00fcbergab den havarierten jungen Mann an die Rettungskr\u00e4fte. Der  Katamaran wurde anschlie\u00dfend durch das Seenotrettungsboot  &#8222;ECKERNF\u00d6RDE&#8220; geborgen und nach Eckernf\u00f6rde verbracht. Auf heutige  Nachfrage hat der junge Mann die Havarie auf der Ostsee Dank der  Retter vor Ort gut \u00fcberstanden.     <\/p>\n<p>Quelle: <a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/70262\/4398714\" target=\"_blank\" rel=\"noopener noreferrer\">presseportal.de<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Neustadt (ots) &#8211; Am Donnerstagabend konnte die Besatzung des Bundespolizeibootes BP 65 &#8222;RH\u00d6N II&#8220; einen Segler aus der 14\u00b0 C<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[20],"tags":[],"class_list":["post-346627","post","type-post","status-publish","format-standard","hentry","category-besondere-neuigkeiten"],"_links":{"self":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts\/346627","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/comments?post=346627"}],"version-history":[{"count":0,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts\/346627\/revisions"}],"wp:attachment":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/media?parent=346627"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/categories?post=346627"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/tags?post=346627"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}