{"id":349251,"date":"2019-09-27T12:35:32","date_gmt":"2019-09-27T12:35:32","guid":{"rendered":"https:\/\/www.hier-luebeck.de\/index.php\/bpoli-see-hilferuf-auf-der-ostsee-404\/"},"modified":"2019-09-27T12:35:32","modified_gmt":"2019-09-27T12:35:32","slug":"bpoli-see-hilferuf-auf-der-ostsee-404","status":"publish","type":"post","link":"https:\/\/hier-luebeck.de\/index.php\/bpoli-see-hilferuf-auf-der-ostsee-404\/","title":{"rendered":"BPOLI-See: Hilferuf auf der Ostsee"},"content":{"rendered":"<p><img decoding=\"async\" class=\"alignleft size-full\" title=\"Seenotrettungsboot \"ONKEL WILLI\" der DGzRS in Zusammenarbeit mit dem Bundespolizeiboot \"R\u00d6HN II\"\" src=\"https:\/\/cache.pressmailing.net\/thumbnail\/story_big\/d0d69631-8616-4770-b229-13e2c4f4cf33\/20190926_151201.jpg\" \/><\/p>\n<p>Neustadt (ots) &#8211;     Beamte der Bundespolizeiinspektion See Neustadt i. H. h\u00f6rten am  26.09.2019 gegen 14:30 Uhr \u00fcber Seefunk auf dem Bundespolizeiboot BP  65 &#8222;R\u00d6HN II&#8220; den Hilferuf einer Segelyacht. Diese war an diesem Tag  von Heiligenhafen aus zu einem Segelt\u00f6rn in die L\u00fcbecker Bucht  aufgebrochen.<!--more--> Kurz vor dem Fahrwasser von Gro\u00dfenbrode meldete die  Besatzung der Segelyacht, dass sich eine Person mit  Herz-Kreislauf-Problemen an Bord befindet und Hilfe ben\u00f6tigt.  Gl\u00fccklicherweise befand sich das Bundespolizeiboot in der N\u00e4he der  Segelyacht und lief sofort die Position an, um Erste Hilfe zu  leisten. Die Bundespolizisten legten sich mit ihrem Boot l\u00e4ngsseits  und gingen an Bord. Es wurden Erste-Hilfe-Ma\u00dfnahmen bei einer Frau an Bord durchgef\u00fchrt. Unterst\u00fctzt wurde der Einsatz durch das  Seenotrettungsboot &#8222;ONKEL WILLI&#8220; der Deutschen Gesellschaft zur  Rettung Schiffbr\u00fcchiger (DGzRS), welches sofort aus Gro\u00dfenbrode  auslief und auch l\u00e4ngsseits an der &#8222;R\u00d6HN II&#8220; festmachte. Das Boot der Seenotretter hatte medizinisches Personal an Bord, die sofort  \u00fcbersetzten und die Besatzung der &#8222;R\u00d6HN II&#8220; abl\u00f6sten. Mit dem Team an Bord verlegte die Segelyacht nach Fehmarn und die Patientin wurde  anschlie\u00dfend an die Rettungskr\u00e4fte an Land \u00fcbergeben. &#8222;ONKEL WILLI&#8220;  \u00fcbernahm die Sicherungsbegleitung der Segelyacht und das  Bundespolizeiboot &#8222;R\u00d6HN II&#8220; konnte nach Beendigung des Einsatzes  seine Seestreife fortsetzen. Die Zusammenarbeit zwischen der  Bundespolizei See und der DGzRS auf See hat auch in diesem Fall  hervorragend funktioniert. Mittlerweile wurde bekannt, dass es der  Patientin wieder bessergeht.     <\/p>\n<p>Quelle: <a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/70262\/4387253\" target=\"_blank\" rel=\"noopener noreferrer\">presseportal.de<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Neustadt (ots) &#8211; Beamte der Bundespolizeiinspektion See Neustadt i. H. h\u00f6rten am 26.09.2019 gegen 14:30 Uhr \u00fcber Seefunk auf dem<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[20],"tags":[],"class_list":["post-349251","post","type-post","status-publish","format-standard","hentry","category-besondere-neuigkeiten"],"_links":{"self":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts\/349251","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/comments?post=349251"}],"version-history":[{"count":0,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts\/349251\/revisions"}],"wp:attachment":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/media?parent=349251"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/categories?post=349251"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/tags?post=349251"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}