{"id":361688,"date":"2020-06-30T12:11:03","date_gmt":"2020-06-30T12:11:03","guid":{"rendered":"https:\/\/www.hier-luebeck.de\/index.php\/pol-sh-afb-ernennungsakt-des-gehobenen-dienstes-145\/"},"modified":"2020-06-30T12:11:03","modified_gmt":"2020-06-30T12:11:03","slug":"pol-sh-afb-ernennungsakt-des-gehobenen-dienstes-145","status":"publish","type":"post","link":"https:\/\/hier-luebeck.de\/index.php\/pol-sh-afb-ernennungsakt-des-gehobenen-dienstes-145\/","title":{"rendered":"POL-SH-AFB: Ernennungsakt des gehobenen Dienstes"},"content":{"rendered":"<p>Eutin (ots) &#8211; 220 Polizeibeamtinnen und Polizeibeamte haben ihr Studium beendet. 196 werden zu Polizeikommissarinnen und Polizeikommissaren ernannt, weitere 24 Kolleginnen und Kollegen steigen vom mittleren in den gehobenen Dienst auf und erhalten ihre Urkunde. Der Anteil der Beamten, die zur Kriminalpolizei geh\u00f6ren, liegt bei 87, und 2 Kolleg*innen geh\u00f6ren der Wasserschutzpolizei an.<!--more--> Die Ministerin f\u00fcr Inneres, l\u00e4ndliche R\u00e4ume, Integration und Gleichstellung, Frau Dr. S\u00fctterlin-Waack wird im Beisein des Landespolizeidirektors Michael Wilksen und des stellvertretenden Leiters der Polizeidirektion f\u00fcr Aus-und Fortbildung und die Bereitschaftspolizei Ralph Garschke die Ehrung der Jahrgangsbesten vornehmen. Aufgrund der Hygienebestimmungen wegen der Corona-Pandemie findet die Veranstaltung erstmalig in Eutin und im wesentlich kleineren Rahmen statt. Angeh\u00f6rige der Absolventen sind nicht dabei, auch die Leiter der Polizeibeh\u00f6rden des polizeilichen Einzeldienstes werden nicht anwesend sein.  Die Damen und Herren Medienvertreter sind zur Teilnahme an diesem Ernennungsakt herzlich eingeladen. Um Anmeldung unter den u.a. Kontaktdaten bis zum 02.07.2020, 15 Uhr, wird gebeten. Beachten Sie bitte die geltenden Hygienebestimmungen. Nur symptomfreie Personen sind zur Teilnahme zugelassen.  <\/p>\n<p>Quelle: <a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43685\/4638609\" target=\"_blank\" rel=\"noopener noreferrer\">presseportal.de<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Eutin (ots) &#8211; 220 Polizeibeamtinnen und Polizeibeamte haben ihr Studium beendet. 196 werden zu Polizeikommissarinnen und Polizeikommissaren ernannt, weitere 24<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[20],"tags":[],"class_list":["post-361688","post","type-post","status-publish","format-standard","hentry","category-besondere-neuigkeiten"],"_links":{"self":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts\/361688","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/comments?post=361688"}],"version-history":[{"count":0,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts\/361688\/revisions"}],"wp:attachment":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/media?parent=361688"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/categories?post=361688"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/tags?post=361688"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}