{"id":370740,"date":"2020-09-16T11:35:39","date_gmt":"2020-09-16T11:35:39","guid":{"rendered":"https:\/\/www.hier-luebeck.de\/index.php\/pol-sh-afb-vereidigung-von-dienstanfaengern-unter-corona-bedingungen-171\/"},"modified":"2020-09-16T11:35:39","modified_gmt":"2020-09-16T11:35:39","slug":"pol-sh-afb-vereidigung-von-dienstanfaengern-unter-corona-bedingungen-171","status":"publish","type":"post","link":"https:\/\/hier-luebeck.de\/index.php\/pol-sh-afb-vereidigung-von-dienstanfaengern-unter-corona-bedingungen-171\/","title":{"rendered":"POL-SH-AFB: Vereidigung von Dienstanf\u00e4ngern unter Corona-Bedingungen"},"content":{"rendered":"<p>Eutin (ots) &#8211; Zu Beginn ihrer Ausbildung werden 401 junge Polizistinnen und Polizisten vereidigt. Nach der Begr\u00fc\u00dfung durch die Leiterin der PD AFB Maren Freyher spricht der Landespolizeidirektor Michael Wilksen ein Gru\u00dfwort. Die Ministerin f\u00fcr Inneres, l\u00e4ndliche R\u00e4ume, Integration und Gleichstellung des Landes Schleswig-Holstein Frau Dr.<!--more--> Sabine S\u00fctterlin-Waack wird die Vereidigung der Anw\u00e4rterinnen und Anw\u00e4rter durchf\u00fchren. Diese haben zum 03. Februar 2020 und zum 03. August 2020 ihre Ausbildung\/ ihr Studium begonnen. Die Veranstaltung findet am 20.09.2020 ab 11.00 Uhr in der Aco Messehalle, Am Friedrichsbrunnen, 24782 B\u00fcdelsdorf statt. Die Damen und Herren Medienvertreter sind zur Teilnahme an dieser Veranstaltung herzlich eingeladen. Um Anmeldung bis zum 18.09.2020, 13 Uhr wird gebeten. Beachten Sie bitte, dass diese Veranstaltung unter besonderen Hygienebedingungen stattfinden muss. Nur symptomfreie Personen sind zur Teilnahme zugelassen.  <\/p>\n<p>Quelle: <a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/43685\/4708118\" target=\"_blank\" rel=\"noopener noreferrer\">presseportal.de<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Eutin (ots) &#8211; Zu Beginn ihrer Ausbildung werden 401 junge Polizistinnen und Polizisten vereidigt. Nach der Begr\u00fc\u00dfung durch die Leiterin<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[20],"tags":[],"class_list":["post-370740","post","type-post","status-publish","format-standard","hentry","category-besondere-neuigkeiten"],"_links":{"self":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts\/370740","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/comments?post=370740"}],"version-history":[{"count":0,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts\/370740\/revisions"}],"wp:attachment":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/media?parent=370740"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/categories?post=370740"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/tags?post=370740"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}