{"id":420101,"date":"2019-09-09T10:00:03","date_gmt":"2019-09-09T10:00:03","guid":{"rendered":"https:\/\/www.hier-luebeck.de\/index.php\/fw-sl-medieneinladung-zur-feuerwehrmusikparade-1452\/"},"modified":"2019-09-09T10:00:03","modified_gmt":"2019-09-09T10:00:03","slug":"fw-sl-medieneinladung-zur-feuerwehrmusikparade-1452","status":"publish","type":"post","link":"https:\/\/hier-luebeck.de\/index.php\/fw-sl-medieneinladung-zur-feuerwehrmusikparade-1452\/","title":{"rendered":"FW-SL: Medieneinladung zur Feuerwehrmusikparade"},"content":{"rendered":"<p>Schleswig (ots) &#8211;   Am Sonntag, den 15. September findet um 18:00 Uhr die diesj\u00e4hrige Kreisfeuerwehr-Musikparade im Festzelt in 24850 H\u00fcsby, unter der Schirmherrschaft des Kreispr\u00e4sidenten Ulrich Br\u00fcggemeier statt.  Seien sie dabei, wenn die Feuerwehrmusikz\u00fcge aus Olpenitz, Westerakeby, Hattstedt-Wobbenb\u00fcll (Kreis NF), Kaltenhof (Kreis RD-Eckernf.<!--more-->) sowie eine Spielgemeinschaft Tetenhusen, Bergenhusen, Bennebek und Meggerdorf spielen.  Karten gibt es bei den teilnehmenden &#8222;Musikz\u00fcgen&#8220;, beim Kreisfeuerwehrverband SL-FL, sowie an der Abendkasse ab 16 Uhr.  Wir bitten die Medien herzlich um Vorank\u00fcndigung und Berichterstattung. Ebenfalls bitten wir die Medien die vor Ort erscheinen, sich vorher unter florian@kfv-slfl.de oder 04621-3056211 anzumelden.  <\/p>\n<p>Quelle: <a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/68035\/4369612\" target=\"_blank\" rel=\"noopener noreferrer\">presseportal.de<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Schleswig (ots) &#8211; Am Sonntag, den 15. September findet um 18:00 Uhr die diesj\u00e4hrige Kreisfeuerwehr-Musikparade im Festzelt in 24850 H\u00fcsby,<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[20],"tags":[],"class_list":["post-420101","post","type-post","status-publish","format-standard","hentry","category-besondere-neuigkeiten"],"_links":{"self":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts\/420101","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/comments?post=420101"}],"version-history":[{"count":0,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts\/420101\/revisions"}],"wp:attachment":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/media?parent=420101"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/categories?post=420101"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/tags?post=420101"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}