{"id":426948,"date":"2019-08-12T09:52:50","date_gmt":"2019-08-12T09:52:50","guid":{"rendered":"https:\/\/www.hier-luebeck.de\/index.php\/fw-oh-kuechenbrand-in-pflegeeinrichtungfeuer-in-aussenstehendem-gebaeude-ein-verletzter-feuerwehrmann-1589\/"},"modified":"2019-08-12T09:52:50","modified_gmt":"2019-08-12T09:52:50","slug":"fw-oh-kuechenbrand-in-pflegeeinrichtungfeuer-in-aussenstehendem-gebaeude-ein-verletzter-feuerwehrmann-1589","status":"publish","type":"post","link":"https:\/\/hier-luebeck.de\/index.php\/fw-oh-kuechenbrand-in-pflegeeinrichtungfeuer-in-aussenstehendem-gebaeude-ein-verletzter-feuerwehrmann-1589\/","title":{"rendered":"FW-OH: K\u00fcchenbrand in Pflegeeinrichtung\nFeuer in au\u00dfenstehendem Geb\u00e4ude. Ein verletzter Feuerwehrmann."},"content":{"rendered":"<p><img decoding=\"async\" class=\"alignleft size-full\" title=\".\" src=\"https:\/\/cache.pressmailing.net\/thumbnail\/story_big\/24c13b66-cdf1-4bd9-b0f0-0eb887a70094\/P%C3%B6nitz_Pflege.jpg\" \/><\/p>\n<p>Lensahn (ots) &#8211;   Um 3:54 Uhr l\u00f6ste die Leitstelle Alarm f\u00fcr die Feuerwehren aus P\u00f6nitz, Scharbeutz und Gleschendorf aus. In einer Pflegeeinrichtung in P\u00f6nitz am See wurde ein K\u00fcchenbrand gemeldet.<!--more--> Aufgrund der besonderen Gegebenheiten erh\u00f6hte die Leitstelle schon w\u00e4hrend des Ausr\u00fcckens der ersten Kr\u00e4fte das Stichwort auf eine Gro\u00dfschadenlage f\u00fcr den Rettungsdienst, so dass auch die Feuerwehr Haffkrug sowie die Schnelleinsatzgruppen (SEG) Ost, West und S\u00fcd, die Technische Einsatzleitung Kreis Ostholstein, Organisatorischer Leiter Rettungsdienst und der Leitende Notarzt alarmiert wurden. Bei Eintreffen der ersten Kr\u00e4fte zeigte sich dann, dass eine K\u00fcche in einem freistehenden Au\u00dfengeb\u00e4ude brannte und somit keine Bewohner in unmittelbarer Gefahr waren. F\u00fcr einen Gro\u00dfteil der alarmierten Kr\u00e4fte konnte schnell Entwarnung gegeben werden. Bereits 25 Minuten nach der Alarmierung konnte Einsatzleiter Patrick B\u00f6nig &#8222;Feuer Aus&#8220; melden. F\u00fcr die rund 80 Einsatzkr\u00e4fte der Feuerwehren der Gemeinde Scharbeutz war der Einsatz nach gut 1,5 Stunden beendet.  Text: Feuerwehr P\u00f6nitz Foto: Feuerwehr P\u00f6nitz  Patrick B\u00f6nig Gemeindewehrf\u00fchrer Feuerwehren der Gemeinde Scharbeutz Am B\u00fcrgerhaus 2 23683 Scharbeutz Tel. 0151-58583103 gwf@feuerwehr80.de www.feuerwehren-gemeinde-scharbeutz.de  <\/p>\n<p>Quelle: <a href=\"https:\/\/www.presseportal.de\/pm\/56143\/4346087\" target=\"_blank\" rel=\"noopener noreferrer\">presseportal.de<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lensahn (ots) &#8211; Um 3:54 Uhr l\u00f6ste die Leitstelle Alarm f\u00fcr die Feuerwehren aus P\u00f6nitz, Scharbeutz und Gleschendorf aus. In<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[20],"tags":[],"class_list":["post-426948","post","type-post","status-publish","format-standard","hentry","category-besondere-neuigkeiten"],"_links":{"self":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts\/426948","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/comments?post=426948"}],"version-history":[{"count":0,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts\/426948\/revisions"}],"wp:attachment":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/media?parent=426948"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/categories?post=426948"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/tags?post=426948"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}