{"id":460801,"date":"2026-07-15T15:12:27","date_gmt":"2026-07-15T13:12:27","guid":{"rendered":"https:\/\/hier-luebeck.de\/index.php\/pol-se-20260715-3-bad-segeberg-unbekannte-entwenden-oeffentliche-kunstobjekte-polizei-sucht-zeugen\/"},"modified":"2026-07-15T15:12:27","modified_gmt":"2026-07-15T13:12:27","slug":"pol-se-20260715-3-bad-segeberg-unbekannte-entwenden-oeffentliche-kunstobjekte-polizei-sucht-zeugen","status":"publish","type":"post","link":"https:\/\/hier-luebeck.de\/index.php\/pol-se-20260715-3-bad-segeberg-unbekannte-entwenden-oeffentliche-kunstobjekte-polizei-sucht-zeugen\/","title":{"rendered":"POL-SE: 20260715.3: Bad Segeberg &#8211; Unbekannte entwenden \u00f6ffentliche Kunstobjekte &#8211; Polizei sucht Zeugen"},"content":{"rendered":"<p>Bad Segeberg (ots) &#8211; <\/p>\n<p>Am Montag (13.07.2026) wurde der Diebstahl einer Kupfersch\u00fcssel von einem Brunnen auf dem Friedhof im Kastanienweg polizeilich bekannt. Kurze Zeit sp\u00e4ter, am Dienstag (14.07.2026) versuchten noch Unbekannte, eine Bronzestatue in der Theodor-Storm-Stra\u00dfe vor dem dortigen Finanzamt zu entwenden. Die Statue lag unweit entfernt auf einem Parkplatz. Die Sch\u00fcssel fehlt noch immer.<\/p>\n<p><!--more--><\/p>\n<p>Die Polizei sucht Zeugen der Taten.<br \/>\nNach derzeitigen Erkenntnissen entwendeten bislang unbekannte T\u00e4ter in der Zeit von Freitag bis Montag (10.07.2026 bis 13.07.2026) eine Kupfersch\u00fcssel, welche sich zur Zierde auf einem Rundbrunnen auf dem Friedhof im Kastanienweg befand. Die Sch\u00fcssel wurde scheinbar aus dem Fundament des Brunnens gewaltsam entfernt.<br \/>\nVermutlich begaben sich die T\u00e4ter mit einem unbekannten Transportfahrzeug in die N\u00e4he des Brunnens, um die Sch\u00fcssel, die einen Durchmesser von etwa 1,5 Metern hatte, abzutransportieren. Der Wert des Objekts wird auf etwa 5.000EUR gesch\u00e4tzt.<br \/>\nZudem wird derzeit davon ausgegangen, dass in der Nacht von Montag auf Dienstag (13.07.2026 bis 14.06.2026), zwischen 20:00 Uhr und 05:45 Uhr, Unbekannte versuchten, die Kunststatue &#8222;Handsteher&#8220;, welche sich vor dem Finanzamt Bad Segeberg befand, zu entwenden.<br \/>\nBei dem Kunstwerk handelt es sich um die etwa zwei Meter hohe bronzene Darstellung eines Mannes, der im Handstand auf einem wackeligen Tisch balanciert.<br \/>\nDie vier Beine dieses Tisches schliffen die T\u00e4ter vermutlich mittels eines noch unbekannten Werkzeugs ab und transportierten das Kunstwerk auf einem Handtrailer f\u00fcr Boote bis zu dem angrenzenden Parkplatz des Segeberger Hallenbads, wo der Trailer unter dem Gewicht der ca. 400kg schweren Statue zusammenbrach. Die T\u00e4ter lie\u00dfen die Statue dort zur\u00fcck.<br \/>\nZu den beiden Taten liegen der Polizei derzeit keine T\u00e4terhinweise vor. Ob ein Zusammenhang zwischen den Taten besteht, ist derzeit Gegenstand der Ermittlungen.<br \/>\nDie Kriminalpolizei Bad Segeberg f\u00fchrt die Ermittlungen zu den beiden Diebst\u00e4hlen und fragt nach Hinweisen zu verd\u00e4chtigen Personen oder Fahrzeugen in Tatortn\u00e4he.<br \/>\nZudem suchen die Ermittler Personen, denen ein solcher Handtrailer in j\u00fcngerer Vergangenheit abhanden gekommen ist.<br \/>\nSachdienliche Mitteilungen zu der Tat oder den T\u00e4tern werden unter der Rufnummer 04551 884-0 entgegengenommen.<br \/>\nEin Bild der abgetrennten Statue liegt der Pressemitteilung bei.<br \/>\nR\u00fcckfragen bitte an:<\/p>\n<p>Polizeidirektion Bad Segeberg<br \/>\n&#8211; Pressestelle &#8211;<br \/>\nDorfstr. 16-18<br \/>\n23795 Bad Segeberg<\/p>\n<p>Niklas St\u00e4\u00df<br \/>\nTelefon: 04551-884-2020<br \/>\nE-Mail: pressestelle.badsegeberg@polizei.landsh.de<\/p>\n<p>Original-Content von: Polizeidirektion Bad Segeberg, \u00fcbermittelt durch news aktuell<\/p>\n<p>Dieser Beitrag wurde automatisch von Presseportal.de zur Verf\u00fcgung gestellt: https:\/\/www.presseportal.de\/blaulicht\/pm\/19027\/6315293<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bad Segeberg (ots) &#8211; Am Montag (13.07.2026) wurde der Diebstahl einer Kupfersch\u00fcssel von einem Brunnen auf dem Friedhof im Kastanienweg<\/p>\n","protected":false},"author":0,"featured_media":460802,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[1527],"tags":[],"class_list":["post-460801","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blaulicht"],"_links":{"self":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts\/460801","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/comments?post=460801"}],"version-history":[{"count":0,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts\/460801\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/media\/460802"}],"wp:attachment":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/media?parent=460801"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/categories?post=460801"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/tags?post=460801"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}