{"id":460809,"date":"2026-07-15T18:40:52","date_gmt":"2026-07-15T16:40:52","guid":{"rendered":"https:\/\/hier-luebeck.de\/?p=460809"},"modified":"2026-07-15T18:40:52","modified_gmt":"2026-07-15T16:40:52","slug":"langeweile-in-den-ferien-diese-forschungsideen-bringen-sommerspass-in-die-kita-den-hort-und-das-zuhause","status":"publish","type":"post","link":"https:\/\/hier-luebeck.de\/index.php\/langeweile-in-den-ferien-diese-forschungsideen-bringen-sommerspass-in-die-kita-den-hort-und-das-zuhause\/","title":{"rendered":"Langeweile in den Ferien? Diese Forschungsideen bringen Sommerspa\u00df in die Kita, den Hort und das Zuhause"},"content":{"rendered":"<p><em>Foto: Ren\u00e9 Arnold \/ \u00a9 Stiftung Kinder forschen<\/em> \u00b7 Alle aufgepasst: Wer nach buntem Ferienspa\u00df und einer eiskalten Abk\u00fchlung sucht, ist hier richtig! Die Sommerideen der Stiftung Kinder forschen vertreiben nicht nur Langeweile, sondern wecken auch die Neugier der Kinder. Die Ideen sind einfach und lassen sich ohne gro\u00dfen Aufwand umsetzen. Ob im Kita-Gruppenraum, drau\u00dfen im Hort oder zuhause: Der Sommer h\u00e4lt f\u00fcr Kinder viele M\u00f6glichkeiten zum Entdecken und Forschen bereit.<!--more-->Warum ver\u00e4ndern sich Schatten im Tagesverlauf?<\/p>\n<p>Im Laufe eines Sommertages werden Schatten mal l\u00e4nger, mal k\u00fcrzer und wandern \u00fcber den Boden. Kinder k\u00f6nnen diese Ver\u00e4nderungen gut beobachten. Dazu suchen sie sich einen sonnigen Platz im Freien und markieren diesen Ort mit Kreide. Ein Kind stellt sich auf die Markierung, die anderen zeichnen dessen Schatten nach. Diesen Vorgang wiederholen die Kinder zu unterschiedlichen Tageszeiten. Wie ver\u00e4ndern sich die Kreideschatten? Woran k\u00f6nnte das liegen?<\/p>\n<h3>Was schwimmt eher: kleines oder gro\u00dfes Obst?<\/h3>\n<p>Mit einer Wasserschale und etwas Obst l\u00e4sst sich jeder Ort zu einem Schwimmlabor verwandeln. Kinder k\u00f6nnen dabei beobachten: Manche Fr\u00fcchte schwimmen an der Oberfl\u00e4che, andere gehen unter. Warum ist das so? Liegt das an der Gr\u00f6\u00dfe? Gemeinsam mit ihren p\u00e4dagogischen Fachkr\u00e4ften oder Eltern legen die Kinder verschiedene Obstsorten wie \u00c4pfel, Weintrauben und Rosinen nacheinander in ein gr\u00f6\u00dferes Glas oder eine Schale mit Wasser und sehen, welche Fr\u00fcchte schwimmen und welche nicht. Entscheidet allein die Gr\u00f6\u00dfe, ob etwas schwimmt?<\/p>\n<h3>Wie wird aus Saft ein cooles Regenbogeneis?<\/h3>\n<p>Buntes Eis am Stiel sorgt nicht nur f\u00fcr Erfrischung an warmen Tagen, sondern begeistert auch wegen seiner Farben. Dazu f\u00fcllen Kinder eine d\u00fcnne Schicht Fruchtsaft (z. B. Orangensaft) in einen leeren Joghurtbecher und stellen ihn ins Gefrierfach. Die Kinder k\u00f6nnen vermuten, wie lange es dauert, bis die Fl\u00fcssigkeit gefriert. Ist die erste Schicht fest, folgt der n\u00e4chste Fruchtsaft in einer anderen Farbe als der erste (z. B. Traubensaft). Die Kinder wiederholen den Vorgang, bis mehrere bunte Schichten \u00fcbereinander entstanden sind.<\/p>\n<h3>Lust auf mehr Forschungsideen?<\/h3>\n<p>Der Alltag steckt voller Ph\u00e4nomene und Dinge, die das Interesse von Kindern wecken. P\u00e4dagogische Fachkr\u00e4fte und Eltern k\u00f6nnen diese Interessen aufgreifen und sie zum Anlass nehmen, um mit den Kindern gemeinsam auf Entdeckungsreise zu gehen. Die Sommerideen und weitere Impulse finden p\u00e4dagogische Fachkr\u00e4fte und Familien \u00fcbrigens<a href=\"https:\/\/cisionone-email.news.stiftung-kinder-forschen.de\/c\/eJw0jMuynSAURL8GZlg8BQcM7sTfuLWFjVI-zs1Gj8nfp0ydzLpX1-ocpU0WZOAYlQ9WDj5oy5cIpjchO2sBJhOUmiYnVQn9k6wbLK-xB-d1UiqA7eW3UtKkJJ0zTidmZasZ1_pL7FA3pCZ89ilkH1IQur3t2j0D3-Jynj-NmS-mR6bH-767dtZyXscs1npkJFFe1NKCR5eR6fGH4HdtcBDO1zHjwfS41hPE8qJTtNe-I9WMePzXqBDMT72QPo9Mj3zHXEEQbggNRc3xH_j-AGa-jOqlVpxiIfxzw5aZlUtFEtuFE6a1y8jbSYj7Y5spgQcvBeqCwqLzYujLINyUdZFKO6Mkf0f9NwAA__8pvnXW\"> auf der Website der Stiftung Kinder forschen<\/a>. Nach Abschluss der Forschungsprojekte gibt es f\u00fcr alle Kinder ein Forschungsdiplom, das Erzieherinnen, Erzieher und Eltern <a href=\"https:\/\/cisionone-email.news.stiftung-kinder-forschen.de\/c\/eJwsy0GO4yAUBNDTwA4LPmDwgkU2PsBcIML8zxgZOxlwYs3tW-nuXelVFQZpkonScwrKeSMn58HwNWACmIzxJJOOWoNKkXz2UWub1OIML2GM1kFSykczyrtSUqckrdUWEjOyF6St_BN7LJVaFw5d8uh88gL622zDp-A1rOf57EzfGMwM5uu6hn6WfL6Ov2IrB1IT-dF6WukYkBjMuVSKuJeDwfyHMG5neXzy_LNqWJ71sd9vZnhi5jthiaJRpdhJFAzfcP8Fpm9ajRIUbyE3-n_FiszItVAT9UULpW1A4v1sRPvnrZcUXXRSEGQShqwT05gnYReELBVYrSR_B_gKAAD__0tFa-M\">hier kostenlos herunterladen<\/a> und ausdrucken k\u00f6nnen.<\/p>\n<h3>\u00dcber die Stiftung Kinder forschen<\/h3>\n<p>Die gemeinn\u00fctzige Stiftung Kinder forschen engagiert sich f\u00fcr gute fr\u00fche Bildung in den Bereichen Mathematik, Informatik, Naturwissenschaften und Technik (MINT) \u2013 mit dem Ziel, M\u00e4dchen und Jungen stark f\u00fcr die Zukunft zu machen und zu nachhaltigem Handeln zu bef\u00e4higen. Gemeinsam mit ihren Netzwerkpartnern vor Ort bietet die Stiftung bundesweit ein Bildungsprogramm an, das p\u00e4dagogische Fach- und Lehrkr\u00e4fte dabei unterst\u00fctzt, Kinder im Kita- und Grundschulalter qualifiziert beim Entdecken, Forschen und Lernen zu begleiten. Die Stiftung Kinder forschen verbessert Bildungschancen, f\u00f6rdert Interesse am MINT-Bereich und professionalisiert daf\u00fcr p\u00e4dagogisches Personal. Partner der Stiftung sind die Siemens Stiftung, die Dietmar Hopp Stiftung und die Dieter Schwarz Stiftung. Gef\u00f6rdert wird sie vom Bundesministerium f\u00fcr Bildung, Familie, Senioren, Frauen und Jugend.<\/p>\n<p>Hier erfahren Sie mehr \u00fcber die Bildungsinitiative Stiftung Kinder forschen: <a href=\"https:\/\/cisionone-email.news.stiftung-kinder-forschen.de\/c\/eJwszMtuwyAQheGnCbuJhpvBCxZ9kgiYmQb5UhWcWH37ylW339H5KaGrLmNUnHSIDucQjVPPZHxEV6hqKXaWPBXMEshjIUdFgqiWpuyDqVrH7CZ8aI22VvTeelNvDkcjXto3bLmt3AcECjVSiDWCGW-33K9Brek8z_s4mhyv_ROWthN3kK8-6pP3O7HamFqGzivnwdAo_cHjH272w-oJjVY9SeefM690c_hs3GF9ceG6XJFxdObtettSc8gBgY0wOPYB5klm8IWMoDbealTvZH4DAAD__y_wV7Q\">www.stiftung-kinder-forschen.de<\/a><br \/>\nInformationen zum Datenschutz und zur Verwendung Ihrer Daten erhalten Sie <a href=\"https:\/\/cisionone-email.news.stiftung-kinder-forschen.de\/c\/eJx0zLFu5CAUheGnMd0dwTUYpqBIM68RYTiskRlnAzjW7tOvJto27ffrnOSljjpIJ-CVdVrerWMtNp8XSGi2lg3uydmUwSZos9qY1gglil-CsRyVckEv8l0pOccojZkNx0nLXhL28knPUCpaJ5tsdMm66Ij7l95vryCq38b43af5beLHxI_rum59lDzO4xft5UholD9ajxuOW8LEjxQGjh63c_zdynGh9B-U8olG34HC2ekDOeMYtby-6PNErTgmfognUgnUUBE6qCT_De__YZrfZrVIVqL53PDnCjVNWm4FjeqJFXG_JYg-GvB8rec1BhusJHAGaRhL9yXfyayJs1RsZiXFl-d_AQAA__9V1HuO\">hier<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Foto: Ren\u00e9 Arnold \/ \u00a9 Stiftung Kinder forschen \u00b7 Alle aufgepasst: Wer nach buntem Ferienspa\u00df und einer eiskalten Abk\u00fchlung sucht,<\/p>\n","protected":false},"author":4994,"featured_media":460810,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[9,14],"tags":[28507,28506],"class_list":["post-460809","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sport-freizeit","category-tipps-informationen","tag-den-hort-und-das-zuhause","tag-langeweile-in-den-ferien-diese-forschungsideen-bringen-sommerspass-in-die-kita"],"_links":{"self":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts\/460809","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/users\/4994"}],"replies":[{"embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/comments?post=460809"}],"version-history":[{"count":1,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts\/460809\/revisions"}],"predecessor-version":[{"id":460811,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts\/460809\/revisions\/460811"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/media\/460810"}],"wp:attachment":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/media?parent=460809"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/categories?post=460809"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/tags?post=460809"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}