{"id":94149,"date":"2013-06-18T16:53:20","date_gmt":"2013-06-18T16:53:20","guid":{"rendered":"http:\/\/www.hier-luebeck.de\/2013\/06\/fw-hl-erneut-lubecker-einsatzkrafte-im-elbe-hochwassereinsatz-174\/"},"modified":"2013-06-18T16:53:20","modified_gmt":"2013-06-18T16:53:20","slug":"fw-hl-erneut-lubecker-einsatzkrafte-im-elbe-hochwassereinsatz-174","status":"publish","type":"post","link":"https:\/\/hier-luebeck.de\/index.php\/fw-hl-erneut-lubecker-einsatzkrafte-im-elbe-hochwassereinsatz-174\/","title":{"rendered":"FW-HL: Erneut L\u00fcbecker Einsatzkr\u00e4fte im Elbe Hochwassereinsatz"},"content":{"rendered":"<p>L\u00fcbeck (ots) &#8211; Stendal &#8211; Durch den Deichbruch bei Fischbeck wurden rund 160 qkm des Landkreises Stendal \u00f6stlich der Elbe \u00fcberflutet.  Mehrere Ortschaften mussten evakuiert werden. Zahlreiche Stra\u00dfen sind nicht mehr passierbar. Die Infrastruktur ist in Mitleidenschaft  gezogen.<!--more-->     Obwohl der Deichbruch bei Fischbeck durch die Versenkung von drei  Schiffen und weiteren Ma\u00dfnahmen eingegrenzt werden konnte, ist im  \u00dcberflutungsgebiet das Wasser noch nicht wesentlich zur\u00fcckgegangen.  Durch den anhaltenden Hochwasserstand der Elbe stauen sich die in die Elbe entw\u00e4ssernden Oberfl\u00e4chengew\u00e4sser im Binnenland auf und auch der Grundwasserspiegel ist angestiegen.     Das Innenministerium Schleswig-Holstein beabsichtigt die Kr\u00e4fte  aus Schleswig-Holstein am 22.06.2013 aus dem Einsatz heraus zu l\u00f6sen  und durch Kr\u00e4fte aus anderen Bundesl\u00e4ndern abl\u00f6sen zu lassen.  Die  Personelle Besetzung der Technischen Einsatzleitung (TEL) vor Ort  wird aber weiterhin durch F\u00fchrungspersonal aus Schleswig-Holsteins  Berufs- und Freiwilligen Feuerwehren gestellt werden. Die 29 Kr\u00e4fte   f\u00fcr die  TEL   werden durch sechs Einsatzkr\u00e4fte von der Feuerwehr  L\u00fcbeck  und  23 Kr\u00e4ften aus Flensburg, Kiel, Kreis Nordfriesland und  Kreis Schleswig-Flensburg abgel\u00f6st. Die Kr\u00e4fte der TEL m\u00fcssen zurzeit noch von einer Einsatzdauer von 7 Tagen ausgehen.     Die TEL wird den Einsatz Deichbau, Deichverteidigung,  Pumpeneinsatz, Mitwirkung bei der Versorgung der Bev\u00f6lkerung,  Unterst\u00fctzung bei der Aufrechterhaltung der Infrastruktur, usw.  f\u00fchren und leiten.     R\u00fcckfragen bitte an:  Feuerwehr L\u00fcbeck Team Pressebetreuer 23554 L\u00fcbeck &#8211; Pressebetreuer &#8211; Bj\u00f6rn von Mateffy Telefon: 0151 \/ 161 33333 E-Mail: b.mateffy@stfv-hl.de http:\/\/www.feuerwehr-luebeck.de<\/p>\n<p>Quelle: <a href=\"http:\/\/www.presseportal.de\/polizeipresse\/pm\/52865\/2496131\/fw-hl-erneut-luebecker-einsatzkraefte-im-elbe-hochwassereinsatz\/api\" target=\"_blank\">presseportal.de<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u00fcbeck (ots) &#8211; Stendal &#8211; Durch den Deichbruch bei Fischbeck wurden rund 160 qkm des Landkreises Stendal \u00f6stlich der Elbe<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[20],"tags":[],"class_list":["post-94149","post","type-post","status-publish","format-standard","hentry","category-besondere-neuigkeiten"],"_links":{"self":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts\/94149","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/comments?post=94149"}],"version-history":[{"count":0,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts\/94149\/revisions"}],"wp:attachment":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/media?parent=94149"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/categories?post=94149"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/tags?post=94149"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}