{"id":96037,"date":"2013-06-05T11:16:56","date_gmt":"2013-06-05T11:16:56","guid":{"rendered":"http:\/\/www.hier-luebeck.de\/2013\/06\/fw-oh-scharbeutz-reetkate-brennt-komplett-nieder-329\/"},"modified":"2013-06-05T11:16:56","modified_gmt":"2013-06-05T11:16:56","slug":"fw-oh-scharbeutz-reetkate-brennt-komplett-nieder-329","status":"publish","type":"post","link":"https:\/\/hier-luebeck.de\/index.php\/fw-oh-scharbeutz-reetkate-brennt-komplett-nieder-329\/","title":{"rendered":"FW-OH: Scharbeutz: Reetkate brennt komplett nieder"},"content":{"rendered":"<p><img decoding=\"async\" class=\"alignleft size-full\" title=\"Foto: Feuerwehr Scharbeutz\" src=\"http:\/\/www.presseportal.de\/bild\/250873-preview-pressemitteilung-ffseinsatz05-06-2013bild3.jpg\" \/><\/p>\n<p>Lensahn (ots) &#8211; Scharbeutz; Es ist 0:10 Uhr als die Integrierte  Leitstelle S\u00fcd in Bad Oldesloe Gro\u00dfalarm f\u00fcr die Freiwillige  Feuerwehr aus Scharbeutz ausgel\u00f6st hat. In der Strandallee sollte ein reetgedeckter Kiosk brennen. &#8222;Auf der Anfahrt best\u00e4tigte sich die  Meldung, die Reetkate brannte bereits lichterloh&#8220;, so der  Einsatzleiter der FFS.<!--more--> &#8222;Aufgrund mehrerer Notrufe wurde das  Alarmierungsstichwort erh\u00f6ht und die Feuerwehren aus Haffkrug und  Sch\u00fcrsdorf mit alarmiert&#8220;, so der Einsatzleiter weiter. Sofort wurde  mit der Brandbek\u00e4mpfung begonnen und der Teleskopmast in Stellung  gebracht. Zur weiteren Unterst\u00fctzung wurden die Feuerwehren Sarkwitz  und Wulfsdorf sowie die feuerwehrtechnische Zentrale aus Lensahn mit  Atemschutzflaschen und Ersatzschl\u00e4uchen nach alarmiert. Mit Hilfe der nachgeforderten Kr\u00e4fte wurde eine Wasserf\u00f6rderung aus der Ostsee  aufgebaut und eine zus\u00e4tzliche Wasserversorgung sichergestellt.  Insgesamt kamen 6 Rohre und \u00fcber 50 Einsatzkr\u00e4fte zum Einsatz. Gegen  4 Uhr konnte &#8222;Feuer aus&#8220; gemeldet werden und gegen 6 Uhr konnten  schlie\u00dflich alle Einsatzkr\u00e4fte einr\u00fccken. W\u00e4hrend der L\u00f6scharbeiten  musste die Bundestra\u00dfe 76 voll gesperrt werden.     R\u00fcckfragen bitte an:     Sebastian Levgr\u00fcn Ortswehrf\u00fchrer     Freiwillige Feuerwehr Scharbeutz Ortswehrf\u00fchrer Sebastian Levgr\u00fcn  Schulstr. 7 23683 Scharbeutz Telefon: 04503 \/ 7 35 45 Telefax: 04503  \/ 70 15 23 Mobil: 01520 \/ 34 45 198 Internet: www.ffs80.de E-Mail:  wehrfuehrer@ffs80.de     Kreisfeuerwehrverband Ostholstein Kreisgesch\u00e4ftsstelle B\u00e4derstrasse 47 23738 Lensahn Pressedienst HBM Hartmut Junge Telefon: 0172 413 73 24 E-Mail: hartmut.junge@kfv-oh.org www.kfv-oh.org<\/p>\n<p>Quelle: <a href=\"http:\/\/www.presseportal.de\/polizeipresse\/pm\/56143\/2486390\/fw-oh-scharbeutz-reetkate-brennt-komplett-nieder\/api\" target=\"_blank\">presseportal.de<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lensahn (ots) &#8211; Scharbeutz; Es ist 0:10 Uhr als die Integrierte Leitstelle S\u00fcd in Bad Oldesloe Gro\u00dfalarm f\u00fcr die Freiwillige<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[20],"tags":[],"class_list":["post-96037","post","type-post","status-publish","format-standard","hentry","category-besondere-neuigkeiten"],"_links":{"self":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts\/96037","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/comments?post=96037"}],"version-history":[{"count":0,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts\/96037\/revisions"}],"wp:attachment":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/media?parent=96037"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/categories?post=96037"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/tags?post=96037"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}