{"id":96038,"date":"2013-04-18T11:47:48","date_gmt":"2013-04-18T11:47:48","guid":{"rendered":"http:\/\/www.hier-luebeck.de\/2013\/04\/fw-oh-dorfvorstand-unterstutzt-die-feuerwehr-scharbeutz-425\/"},"modified":"2013-04-18T11:47:48","modified_gmt":"2013-04-18T11:47:48","slug":"fw-oh-dorfvorstand-unterstutzt-die-feuerwehr-scharbeutz-425","status":"publish","type":"post","link":"https:\/\/hier-luebeck.de\/index.php\/fw-oh-dorfvorstand-unterstutzt-die-feuerwehr-scharbeutz-425\/","title":{"rendered":"FW-OH: Dorfvorstand unterst\u00fctzt die Feuerwehr Scharbeutz"},"content":{"rendered":"<p><img decoding=\"async\" class=\"alignleft size-full\" title=\"Bild Feuerwehr Scharbeutz: \nvon links; Hans Karpinski und Michael P\u00e4tau, Dorfvorstand, Sebastian Levgr\u00fcn und Holger Schimanski, FFS\" src=\"http:\/\/www.presseportal.de\/bild\/246784-preview-pressemitteilung-zpfile001.jpg\" \/><\/p>\n<p>Lensahn (ots) &#8211; Scharbeutz; Der Dorfvorstand Scharbeutz  unterst\u00fctzt erneut aktiv die Freiwillige Feuerwehr Scharbeutz. Seit  mehreren Jahren zeigt der Dorfvorstand und die Freiwillige Feuerwehr  Scharbeutz sich als starkes Team und arbeiten stets gemeinsam Hand in Hand f\u00fcr den Ort Scharbeutz.<!--more--> Dieses Mal spendet der Dorfvorstand von  den Standgeb\u00fchren des Hallenflohmarktes im M\u00e4rz &#8222;Kranzubeh\u00f6r&#8220; f\u00fcr das Teleskopmastfahrzeug. Das neue Hebegeschirr im Wert von 200 EUR soll  das neue Hubrettungsger\u00e4t von der Feuerwehr Scharbeutz f\u00fcr technische Hilfeleistungen optimieren. Michael P\u00e4tau und Hans Karpinski vom  Dorfvorstand \u00fcbergeben das Kranzubeh\u00f6r an den Ortswehrf\u00fchrer  Sebastian Levgr\u00fcn und an den Ger\u00e4tewart Holger Schimanski. &#8222;Wir  setzen uns super gerne f\u00fcr die Feuerwehr ein, denn Sie sind immer f\u00fcr die B\u00fcrger da und sie sind ein super Team&#8220;, berichtet Dorfvorsteher  Michael P\u00e4tau stolz. Bereits am Mittwoch, den1.Mai werden der  Dorfvorstand und die Feuerwehr wieder gemeinsam den Maibaum auf dem  Seebr\u00fcckenvorplatz in Scharbeutz aufstellen.     R\u00fcckfragen bitte an:  Freiwillige Feuerwehr Scharbeutz Ortswehrf\u00fchrer Sebastian Levgr\u00fcn Schulstr. 7 23683 Scharbeutz Telefon: 04503 \/ 7 35 45 Telefax: 04503 \/ 70 15 23 Mobil: 01520 \/ 34 45 198 Internet: www.ffs80.de E-Mail: wehrfuehrer@ffs80.de  Kreisfeuerwehrverband Ostholstein Kreisgesch\u00e4ftsstelle B\u00e4derstrasse 47 23738 Lensahn Pressedienst HBM Hartmut Junge Telefon: 0172 413 73 24 E-Mail: hartmut.junge@kfv-oh.org www.kfv-oh.org<\/p>\n<p>Quelle: <a href=\"http:\/\/www.presseportal.de\/polizeipresse\/pm\/56143\/2453426\/fw-oh-dorfvorstand-unterstuetzt-die-feuerwehr-scharbeutz\/api\" target=\"_blank\">presseportal.de<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lensahn (ots) &#8211; Scharbeutz; Der Dorfvorstand Scharbeutz unterst\u00fctzt erneut aktiv die Freiwillige Feuerwehr Scharbeutz. Seit mehreren Jahren zeigt der Dorfvorstand<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[20],"tags":[],"class_list":["post-96038","post","type-post","status-publish","format-standard","hentry","category-besondere-neuigkeiten"],"_links":{"self":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts\/96038","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/comments?post=96038"}],"version-history":[{"count":0,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/posts\/96038\/revisions"}],"wp:attachment":[{"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/media?parent=96038"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/categories?post=96038"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hier-luebeck.de\/index.php\/wp-json\/wp\/v2\/tags?post=96038"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}